{"id":1677,"date":"2020-01-16T14:38:14","date_gmt":"2020-01-16T14:38:14","guid":{"rendered":"https:\/\/progetic.com\/hotel-casa-del-castell\/"},"modified":"2024-07-22T07:59:25","modified_gmt":"2024-07-22T07:59:25","slug":"hotel-casa-del-castell","status":"publish","type":"post","link":"https:\/\/progetic.com\/es\/edificis-terciaris\/hotel-casa-del-castell\/","title":{"rendered":"Hotel Casa del Castell"},"content":{"rendered":"\n<div class=\"wp-block-atomic-blocks-ab-container header_inside_02 ab-block-container alignfull\"><div class=\"ab-container-inside\"><div class=\"ab-container-image-wrap\"><img decoding=\"async\" class=\"ab-container-image has-background-dim-100 has-background-dim\" src=\"https:\/\/progetic.com\/wp-content\/uploads\/2019\/12\/bg_header_project.png\" alt=\"\"\/><\/div><div class=\"ab-container-content\" style=\"max-width:1600px\">\n<div class=\"wp-block-atomic-blocks-ab-columns ab-layout-columns-2 ab-2-col-equal ab-columns-center\"><div class=\"ab-layout-column-wrap ab-block-layout-column-gap-5 ab-is-responsive-column\" style=\"max-width:1140px\">\n<div class=\"wp-block-atomic-blocks-ab-column ab-block-layout-column\"><div class=\"ab-block-layout-column-inner\">\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-atomic-blocks-ab-column ab-block-layout-column ab-is-vertically-aligned-bottom\"><div class=\"ab-block-layout-column-inner\">\n<h2 class=\"subtitle_proyect wp-block-heading\"><strong>Proyecto<\/strong> nZEB, Passivhaus y ingenier\u00eda instalaciones <\/h2>\n\n\n\n<h1 class=\"title_proyect wp-block-heading\">Hotel Casa del Castell<\/h1>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>#kt-layout-id_efc873-1c > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_efc873-1c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_efc873-1c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}#kt-layout-id_efc873-1c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){#kt-layout-id_efc873-1c > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_efc873-1c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignnone\"><div id=\"kt-layout-id_efc873-1c\" class=\"kt-row-layout-inner  kt-layout-id_efc873-1c\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-left-golden kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_4cf550-95 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_4cf550-95 > .kt-inside-inner-col,.kadence-column_4cf550-95 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_4cf550-95 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_4cf550-95 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_4cf550-95 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_4cf550-95 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_4cf550-95{position:relative;}@media all and (max-width: 1024px){.kadence-column_4cf550-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_4cf550-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_4cf550-95\"><div class=\"kt-inside-inner-col\"><style>.kb-gallery-id-_7d208f-5a .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-_7d208f-5a .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-wrap-id-_7d208f-5a.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-_7d208f-5a.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;}<\/style><div class=\"kb-gallery-wrap-id-_7d208f-5a alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-slider kb-gallery-id-_7d208f-5a kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel splide kt-carousel-container-dotstyle-dark kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-fade=\"true\" data-slider-dots=\"true\" data-slider-type=\"slider\" data-slider-hover-pause=\"false\" data-slider-auto=\"1\" data-slider-speed=\"2080\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"kt-blocks-carousel-init kb-blocks-slider splide__list\"><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"518\" src=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg\"   alt=\"Casa Castell\" data-full-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg\" data-light-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg\" data-id=\"535\" class=\"wp-image-535 skip-lazy\" srcset=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg 828w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01-300x188.jpg 300w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01-768x480.jpg 768w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01-200x125.jpg 200w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"518\" src=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_02.jpg\"   alt=\"Casa Castell\" data-full-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_02.jpg\" data-light-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_02.jpg\" data-id=\"534\" class=\"wp-image-534 skip-lazy\" srcset=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_02.jpg 828w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_02-300x188.jpg 300w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_02-768x480.jpg 768w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_02-200x125.jpg 200w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"518\" src=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_03.jpg\"   alt=\"Casa Castell\" data-full-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_03.jpg\" data-light-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_03.jpg\" data-id=\"533\" class=\"wp-image-533 skip-lazy\" srcset=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_03.jpg 828w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_03-300x188.jpg 300w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_03-768x480.jpg 768w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_03-200x125.jpg 200w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"518\" src=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_04.jpg\"   alt=\"Casa Castell\" data-full-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_04.jpg\" data-light-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_04.jpg\" data-id=\"532\" class=\"wp-image-532 skip-lazy\" srcset=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_04.jpg 828w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_04-300x188.jpg 300w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_04-768x480.jpg 768w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_04-200x125.jpg 200w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"518\" src=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_05.jpg\"   alt=\"Casa Castell\" data-full-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_05.jpg\" data-light-image=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_05.jpg\" data-id=\"531\" class=\"wp-image-531 skip-lazy\" srcset=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_05.jpg 828w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_05-300x188.jpg 300w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_05-768x480.jpg 768w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_05-200x125.jpg 200w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\n\n\n<p><strong>Descripci\u00f3n <\/strong><\/p>\n\n\n\n<p>Consultor\u00eda energ\u00e9tica e ingenier\u00eda de instalaciones para un hotel de\nenerg\u00eda casi nula &#8211; NZEB, dise\u00f1ado bajo el Est\u00e1ndar Passivhaus.<\/p>\n\n\n\n<p>La consultor\u00eda energ\u00e9tica incluye la simulaci\u00f3n termodin\u00e1mica en\nDesignBuilder (EnergyPlus) y en PHPP, dise\u00f1o y asesor\u00eda en materiales,\nenvolvente t\u00e9rmica, estrategias de protecci\u00f3n contra el sobrecalentamiento en\nverano.<\/p>\n\n\n\n<p>El proyecto de instalaciones se dise\u00f1a con aerotermia para la producci\u00f3n de ACS y la climatizaci\u00f3n (paredes radiantes), ventilaci\u00f3n mec\u00e1nica de doble flujo con recuperaci\u00f3n de calor y control integral de estas instalaciones con sistema de dom\u00f3tica KNX. Tambi\u00e9n se ha previsto el apoyo de la bomba de calor con energ\u00eda solar t\u00e9rmica. <\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column_0a1d10-67 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_0a1d10-67 > .kt-inside-inner-col,.kadence-column_0a1d10-67 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_0a1d10-67 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_0a1d10-67 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_0a1d10-67 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_0a1d10-67 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_0a1d10-67{position:relative;}@media all and (max-width: 1024px){.kadence-column_0a1d10-67 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_0a1d10-67 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-2 kadence-column_0a1d10-67\"><div class=\"kt-inside-inner-col\">\n<p><strong>A\u00f1o: <\/strong>2014<\/p>\n\n\n\n<p><strong>Lugar:<\/strong> Mora d\u2019Ebre, Ribera d\u2019Ebre <\/p>\n\n\n\n<p><strong>Servicios \/ Instalaciones realizadas:<\/strong><br>Consultor\u00eda energ\u00e9tica Passivhaus, ingenier\u00eda de instalaciones <\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Consultor\u00eda energ\u00e9tica e ingenier\u00eda de instalaciones para un hotel de energ\u00eda casi nula &#8211; NZEB, dise\u00f1ado bajo el Est\u00e1ndar Passivhaus.<\/p>\n","protected":false},"author":1,"featured_media":1446,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[20,60,54],"tags":[],"class_list":{"0":"post-1677","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-edificis-terciaris","8":"category-passivhaus-es","9":"category-ingenieria-de-instalaciones","11":"with-featured-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hotel Casa del Castell | Progetic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel Casa del Castell | Progetic\" \/>\n<meta property=\"og:description\" content=\"Consultor\u00eda energ\u00e9tica e ingenier\u00eda de instalaciones para un hotel de energ\u00eda casi nula - NZEB, dise\u00f1ado bajo el Est\u00e1ndar Passivhaus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/\" \/>\n<meta property=\"og:site_name\" content=\"Progetic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/ProGETIC-Energy-Solutions\/359464210793572\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-16T14:38:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T07:59:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"518\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ideadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PRoGETIC1\" \/>\n<meta name=\"twitter:site\" content=\"@PRoGETIC1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ideadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/\"},\"author\":{\"name\":\"ideadmin\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#\\\/schema\\\/person\\\/041af7e621061694b49ff7d28e3c4544\"},\"headline\":\"Hotel Casa del Castell\",\"datePublished\":\"2020-01-16T14:38:14+00:00\",\"dateModified\":\"2024-07-22T07:59:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/\"},\"wordCount\":163,\"publisher\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/casa_castell_01.jpg\",\"articleSection\":[\"Edificis terciaris\",\"Passivhaus\",\"Proyectos Ingenier\u00eda de instalaciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/\",\"url\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/\",\"name\":\"Hotel Casa del Castell | Progetic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/casa_castell_01.jpg\",\"datePublished\":\"2020-01-16T14:38:14+00:00\",\"dateModified\":\"2024-07-22T07:59:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/casa_castell_01.jpg\",\"contentUrl\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/casa_castell_01.jpg\",\"width\":828,\"height\":518,\"caption\":\"Casa Castell\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/edificios-terciarios\\\/hotel-casa-del-castell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/progetic.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel Casa del Castell\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#website\",\"url\":\"https:\\\/\\\/progetic.com\\\/\",\"name\":\"Progetic\",\"description\":\"Serveis d\u2019enginyeria i consultoria per a edificis de consum gaireb\u00e9 nul i Passivhaus\",\"publisher\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#organization\",\"name\":\"Progetic Consultoria Enginyeria\",\"url\":\"https:\\\/\\\/progetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo_Progetic.svg\",\"contentUrl\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo_Progetic.svg\",\"width\":1,\"height\":1,\"caption\":\"Progetic Consultoria Enginyeria\"},\"image\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/ProGETIC-Energy-Solutions\\\/359464210793572\",\"https:\\\/\\\/x.com\\\/PRoGETIC1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#\\\/schema\\\/person\\\/041af7e621061694b49ff7d28e3c4544\",\"name\":\"ideadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g\",\"caption\":\"ideadmin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel Casa del Castell | Progetic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/","og_locale":"es_ES","og_type":"article","og_title":"Hotel Casa del Castell | Progetic","og_description":"Consultor\u00eda energ\u00e9tica e ingenier\u00eda de instalaciones para un hotel de energ\u00eda casi nula - NZEB, dise\u00f1ado bajo el Est\u00e1ndar Passivhaus.","og_url":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/","og_site_name":"Progetic","article_publisher":"https:\/\/www.facebook.com\/pages\/ProGETIC-Energy-Solutions\/359464210793572","article_published_time":"2020-01-16T14:38:14+00:00","article_modified_time":"2024-07-22T07:59:25+00:00","og_image":[{"width":828,"height":518,"url":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg","type":"image\/jpeg"}],"author":"ideadmin","twitter_card":"summary_large_image","twitter_creator":"@PRoGETIC1","twitter_site":"@PRoGETIC1","twitter_misc":{"Escrito por":"ideadmin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/#article","isPartOf":{"@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/"},"author":{"name":"ideadmin","@id":"https:\/\/progetic.com\/#\/schema\/person\/041af7e621061694b49ff7d28e3c4544"},"headline":"Hotel Casa del Castell","datePublished":"2020-01-16T14:38:14+00:00","dateModified":"2024-07-22T07:59:25+00:00","mainEntityOfPage":{"@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/"},"wordCount":163,"publisher":{"@id":"https:\/\/progetic.com\/#organization"},"image":{"@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/#primaryimage"},"thumbnailUrl":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg","articleSection":["Edificis terciaris","Passivhaus","Proyectos Ingenier\u00eda de instalaciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/","url":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/","name":"Hotel Casa del Castell | Progetic","isPartOf":{"@id":"https:\/\/progetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/#primaryimage"},"image":{"@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/#primaryimage"},"thumbnailUrl":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg","datePublished":"2020-01-16T14:38:14+00:00","dateModified":"2024-07-22T07:59:25+00:00","breadcrumb":{"@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/#primaryimage","url":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg","contentUrl":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01.jpg","width":828,"height":518,"caption":"Casa Castell"},{"@type":"BreadcrumbList","@id":"https:\/\/progetic.com\/es\/edificios-terciarios\/hotel-casa-del-castell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/progetic.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hotel Casa del Castell"}]},{"@type":"WebSite","@id":"https:\/\/progetic.com\/#website","url":"https:\/\/progetic.com\/","name":"Progetic","description":"Serveis d\u2019enginyeria i consultoria per a edificis de consum gaireb\u00e9 nul i Passivhaus","publisher":{"@id":"https:\/\/progetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/progetic.com\/#organization","name":"Progetic Consultoria Enginyeria","url":"https:\/\/progetic.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/progetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/progetic.com\/wp-content\/uploads\/2019\/12\/Logo_Progetic.svg","contentUrl":"https:\/\/progetic.com\/wp-content\/uploads\/2019\/12\/Logo_Progetic.svg","width":1,"height":1,"caption":"Progetic Consultoria Enginyeria"},"image":{"@id":"https:\/\/progetic.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/ProGETIC-Energy-Solutions\/359464210793572","https:\/\/x.com\/PRoGETIC1"]},{"@type":"Person","@id":"https:\/\/progetic.com\/#\/schema\/person\/041af7e621061694b49ff7d28e3c4544","name":"ideadmin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g","caption":"ideadmin"}}]}},"featured_image_src":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01-600x400.jpg","featured_image_src_square":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/casa_castell_01-600x518.jpg","author_info":{"display_name":"ideadmin","author_link":"https:\/\/progetic.com\/es\/author\/ideadmin\/"},"_links":{"self":[{"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/posts\/1677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/comments?post=1677"}],"version-history":[{"count":2,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/posts\/1677\/revisions"}],"predecessor-version":[{"id":2187,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/posts\/1677\/revisions\/2187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/media\/1446"}],"wp:attachment":[{"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/media?parent=1677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/categories?post=1677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/tags?post=1677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}