{"id":1528,"date":"2020-01-28T12:30:02","date_gmt":"2020-01-28T12:30:02","guid":{"rendered":"https:\/\/progetic.com\/sidebar-blog-es\/"},"modified":"2020-02-21T17:13:51","modified_gmt":"2020-02-21T17:13:51","slug":"bombas-de-calor-para-viviendas-de-baja-demanda-termica","status":"publish","type":"post","link":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/","title":{"rendered":"Bombas de calor para viviendas de baja demanda t\u00e9rmica"},"content":{"rendered":"\n<div class=\"wp-block-atomic-blocks-ab-container header_inside_02 header_height_03 animated fadeInUp slow ab-block-container alignfull\"><div class=\"ab-container-inside\"><div class=\"ab-container-image-wrap\"><img decoding=\"async\" class=\"ab-container-image has-background-dim-100 has-background-dim\" src=\"https:\/\/progetic.com\/wp-content\/uploads\/2019\/12\/header_blog.jpg\" alt=\"Blog\"\/><\/div><div class=\"ab-container-content\" style=\"max-width:1600px\">\n<div class=\"wp-block-atomic-blocks-ab-columns ab-layout-columns-2 ab-2-col-equal ab-columns-center\"><div class=\"ab-layout-column-wrap ab-block-layout-column-gap-1 ab-is-responsive-column\" style=\"max-width:1140px\">\n<div class=\"wp-block-atomic-blocks-ab-column ab-block-layout-column\"><div class=\"ab-block-layout-column-inner\">\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-atomic-blocks-ab-column ab-block-layout-column ab-is-vertically-aligned-bottom\"><div class=\"ab-block-layout-column-inner\">\n<h2 class=\"has-text-align-right subtitle_proyect wp-block-heading\">Blog<\/h2>\n\n\n\n<h1 class=\"has-text-align-right title_proyect wp-block-heading\">Bombas de calor para viviendas de baja demanda t\u00e9rmica<\/h1>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_efc873-1c > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_efc873-1c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_efc873-1c > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(75% - ((40px * 1 )\/2)))minmax(0, calc(25% - ((40px * 1 )\/2)));}#kt-layout-id_efc873-1c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){#kt-layout-id_efc873-1c > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_efc873-1c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignnone\"><div id=\"kt-layout-id_efc873-1c\" class=\"kt-row-layout-inner  kt-layout-id_efc873-1c\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-gutter-wide kt-v-gutter-default kt-row-valign-top kt-row-layout-left-golden kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row kt-custom-first-width-75 kt-custom-second-width-25\"><style>.kadence-column_4cf550-95 > .kt-inside-inner-col{padding-right:70px;}.kadence-column_4cf550-95 > .kt-inside-inner-col{border-top-width:0px;border-right-width:1px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_4cf550-95 > .kt-inside-inner-col,.kadence-column_4cf550-95 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_4cf550-95 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_4cf550-95 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_4cf550-95 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_4cf550-95 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_4cf550-95{position:relative;}@media all and (max-width: 1024px){.kadence-column_4cf550-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_4cf550-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_4cf550-95 column_blog\"><div class=\"kt-inside-inner-col\">\n<p>Cada d\u00eda es m\u00e1s com\u00fan el uso de las bombas de calor para la producci\u00f3n de climatizaci\u00f3n y agua caliente sanitaria (ACS) en las viviendas. Su elevado rendimiento energ\u00e9tico y el hecho de que se alimenten con electricidad, las hace ideales para integrarse en viviendas, especialmente en las de baja demanda energ\u00e9tica. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"518\" src=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01.jpg\" alt=\"Progetic bomba de calor\" class=\"wp-image-783\" srcset=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01.jpg 828w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01-300x188.jpg 300w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01-768x480.jpg 768w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01-200x125.jpg 200w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/figure>\n\n\n\n<p>La bomba de calor basa su funcionamiento en el movimiento del calor des de un foco caliente a un foco fr\u00edo. As\u00ed, durante el invierno extrae calor del aire exterior o del subsuelo y lo transporta al interior del inmueble, y durante el verano tiene el funcionamiento a la inversa. Para conseguir este transporte de calor utiliza un gas refrigerante que tiene la particularidad de tener una temperatura de ebullici\u00f3n muy baja. Sometiendo el gas a unas condiciones cambiantes de presi\u00f3n conseguimos que cuando evapore absorba aire caliente y cuando condense lo libere. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"518\" src=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_02.jpg\" alt=\"Progetic bomba de calor\" class=\"wp-image-784\" srcset=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_02.jpg 828w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_02-300x188.jpg 300w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_02-768x480.jpg 768w, https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_02-200x125.jpg 200w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/figure>\n\n\n\n<p>Antiguamente las bombas de calor ten\u00edan un funcionamiento todo nada, es decir, entregaban toda su potencia nominal o estaban paradas. Actualmente la mayor\u00eda de ellas disponen de compresores con variadores de frecuencia que permiten ajustar la potencia nominal en funci\u00f3n de la demanda. A\u00fan con esta mejora en el funcionamiento, hay una serie de aspectos importantes a tener en cuenta para dise\u00f1ar el sistema hidr\u00e1ulico de control:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Aunque dispongan de variador de frecuencia, el ciclo termodin\u00e1mico del refrigerante necesita un tiempo m\u00ednimo de funcionamiento, que obliga a una hist\u00e9resis en el funcionamiento del term\u00f3stato que conviene que tenga un per\u00edodo m\u00ednimo de 30 minutos.<\/li><li>Aunque los fabricantes indiquen en muchos casos, la no necesidad de un dep\u00f3sito de inercia, cuando disponemos de sistemas terminales de poca inercia, y la demanda t\u00e9rmica en esos momentos sea baja, conviene tener un cierto volumen de agua para permitir la hist\u00e9resis que se indicaba en el apartado anterior.<\/li><li>La modulaci\u00f3n de la potencia tiene un m\u00ednimo que suele estar alrededor del 30% de su potencia nominal. Es importante tenerlo en cuenta para dimensionar el dep\u00f3sito de inercia y los sistemas principales.<\/li><li>Por lo comentado en los apartados anteriores, es importante ajustar la potencia nominal de la bomba de calor a la carga t\u00e9rmica de la vivienda. Si se sobredimensiona, nos encontramos que la demanda estar\u00e1 mayoritariamente por debajo del 30% de la potencia de la bomba de calor y provocaremos demasiados arranques y paradas del compresor, reduciendo su vida \u00fatil, y obteniendo rendimientos t\u00e9rmicos muy bajos.<\/li><li>Tanto la potencia t\u00e9rmica de la bomba de calor como su rendimiento depende de dos temperaturas: la temperatura del aire exterior (bombas de calor aerot\u00e9rmicas) y la temperatura del agua de climatizaci\u00f3n. Se tiene que verificar que en las condiciones m\u00e1ximas de temperatura en el invierno y verano, la potencia de la bomba de calor ser\u00e1 suficiente para cubrir la carga t\u00e9rmica m\u00e1xima de la vivienda.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column_0a1d10-67 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_0a1d10-67 > .kt-inside-inner-col,.kadence-column_0a1d10-67 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_0a1d10-67 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_0a1d10-67 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_0a1d10-67 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_0a1d10-67 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_0a1d10-67{position:relative;}@media all and (max-width: 1024px){.kadence-column_0a1d10-67 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_0a1d10-67 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-2 kadence-column_0a1d10-67\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-atomic-blocks-ab-container sidebar_blog ab-block-container\"><div class=\"ab-container-inside\"><div class=\"ab-container-content\"><form role=\"search\" method=\"get\" action=\"https:\/\/progetic.com\/es\/\" class=\"wp-block-search__button-outside wp-block-search__text-button wp-block-search\"    ><label class=\"wp-block-search__label\" for=\"wp-block-search__input-1\" >Buscar<\/label><div class=\"wp-block-search__inside-wrapper\" ><input class=\"wp-block-search__input\" id=\"wp-block-search__input-1\" placeholder=\"\" value=\"\" type=\"search\" name=\"s\" required \/><button aria-label=\"Buscar\" class=\"wp-block-search__button wp-element-button\" type=\"submit\" >Buscar<\/button><\/div><\/form>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">\u00daltimos art\u00edculos<\/h4>\n\n\n<ul class=\"wp-block-latest-posts__list has-dates last_posts wp-block-latest-posts\"><li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/progetic.com\/es\/blog\/como-pagar-50e-al-ano-en-calefaccion\/\">C\u00f3mo pagar 50\u20ac al a\u00f1o en calefacci\u00f3n<\/a><time datetime=\"2020-02-11T15:06:10+00:00\" class=\"wp-block-latest-posts__post-date\">11 de febrero de 2020<\/time><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/progetic.com\/es\/blog-es\/auditorias-energeticas-para-empresas\/\">Auditor\u00edas energ\u00e9ticas para empresas<\/a><time datetime=\"2020-02-11T16:22:35+00:00\" class=\"wp-block-latest-posts__post-date\">11 de febrero de 2020<\/time><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/\">Bombas de calor para viviendas de baja demanda t\u00e9rmica<\/a><time datetime=\"2020-01-28T12:30:02+00:00\" class=\"wp-block-latest-posts__post-date\">28 de enero de 2020<\/time><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/progetic.com\/es\/blog-es\/isobio-calculo-higrotermico-y-validacion-de-un-panel-aislante-estructural-con-materiales-de-origen-biologico\/\">ISOBIO: c\u00e1lculo higrot\u00e9rmico y validaci\u00f3n de un panel aislante estructural con materiales de origen biol\u00f3gico<\/a><time datetime=\"2020-02-11T17:26:04+00:00\" class=\"wp-block-latest-posts__post-date\">11 de febrero de 2020<\/time><\/li>\n<\/ul>\n\n\n<p><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cada d\u00eda es m\u00e1s com\u00fan el uso de las bombas de calor para la producci\u00f3n de climatizaci\u00f3n y agua caliente sanitaria (ACS) en las viviendas. Su elevado rendimiento energ\u00e9tico y el hecho de que se alimenten con electricidad, las hace ideales para integrarse en viviendas, especialmente en las de baja demanda energ\u00e9tica. <\/p>\n","protected":false},"author":1,"featured_media":1306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[41],"tags":[],"class_list":{"0":"post-1528","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-blog-es","9":"with-featured-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bombas de calor para viviendas de baja demanda t\u00e9rmica | Progetic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bombas de calor para viviendas de baja demanda t\u00e9rmica | Progetic\" \/>\n<meta property=\"og:description\" content=\"Cada d\u00eda es m\u00e1s com\u00fan el uso de las bombas de calor para la producci\u00f3n de climatizaci\u00f3n y agua caliente sanitaria (ACS) en las viviendas. Su elevado rendimiento energ\u00e9tico y el hecho de que se alimenten con electricidad, las hace ideales para integrarse en viviendas, especialmente en las de baja demanda energ\u00e9tica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/\" \/>\n<meta property=\"og:site_name\" content=\"Progetic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/ProGETIC-Energy-Solutions\/359464210793572\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-28T12:30:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-21T17:13:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"518\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ideadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PRoGETIC1\" \/>\n<meta name=\"twitter:site\" content=\"@PRoGETIC1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ideadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/\"},\"author\":{\"name\":\"ideadmin\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#\\\/schema\\\/person\\\/041af7e621061694b49ff7d28e3c4544\"},\"headline\":\"Bombas de calor para viviendas de baja demanda t\u00e9rmica\",\"datePublished\":\"2020-01-28T12:30:02+00:00\",\"dateModified\":\"2020-02-21T17:13:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/\"},\"wordCount\":517,\"publisher\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/progetic_bomba_calor_01.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/\",\"url\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/\",\"name\":\"Bombas de calor para viviendas de baja demanda t\u00e9rmica | Progetic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/progetic_bomba_calor_01.jpg\",\"datePublished\":\"2020-01-28T12:30:02+00:00\",\"dateModified\":\"2020-02-21T17:13:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/progetic_bomba_calor_01.jpg\",\"contentUrl\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/progetic_bomba_calor_01.jpg\",\"width\":828,\"height\":518,\"caption\":\"Figura 4: C\u00e0lcul de pont t\u00e8rmic, Solera > Mur fa\u00e7ana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progetic.com\\\/es\\\/blog-es\\\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/progetic.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bombas de calor para viviendas de baja demanda t\u00e9rmica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#website\",\"url\":\"https:\\\/\\\/progetic.com\\\/\",\"name\":\"Progetic\",\"description\":\"Serveis d\u2019enginyeria i consultoria per a edificis de consum gaireb\u00e9 nul i Passivhaus\",\"publisher\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#organization\",\"name\":\"Progetic Consultoria Enginyeria\",\"url\":\"https:\\\/\\\/progetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo_Progetic.svg\",\"contentUrl\":\"https:\\\/\\\/progetic.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo_Progetic.svg\",\"width\":1,\"height\":1,\"caption\":\"Progetic Consultoria Enginyeria\"},\"image\":{\"@id\":\"https:\\\/\\\/progetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/ProGETIC-Energy-Solutions\\\/359464210793572\",\"https:\\\/\\\/x.com\\\/PRoGETIC1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progetic.com\\\/#\\\/schema\\\/person\\\/041af7e621061694b49ff7d28e3c4544\",\"name\":\"ideadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g\",\"caption\":\"ideadmin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bombas de calor para viviendas de baja demanda t\u00e9rmica | Progetic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/","og_locale":"es_ES","og_type":"article","og_title":"Bombas de calor para viviendas de baja demanda t\u00e9rmica | Progetic","og_description":"Cada d\u00eda es m\u00e1s com\u00fan el uso de las bombas de calor para la producci\u00f3n de climatizaci\u00f3n y agua caliente sanitaria (ACS) en las viviendas. Su elevado rendimiento energ\u00e9tico y el hecho de que se alimenten con electricidad, las hace ideales para integrarse en viviendas, especialmente en las de baja demanda energ\u00e9tica.","og_url":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/","og_site_name":"Progetic","article_publisher":"https:\/\/www.facebook.com\/pages\/ProGETIC-Energy-Solutions\/359464210793572","article_published_time":"2020-01-28T12:30:02+00:00","article_modified_time":"2020-02-21T17:13:51+00:00","og_image":[{"width":828,"height":518,"url":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01.jpg","type":"image\/jpeg"}],"author":"ideadmin","twitter_card":"summary_large_image","twitter_creator":"@PRoGETIC1","twitter_site":"@PRoGETIC1","twitter_misc":{"Escrito por":"ideadmin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/#article","isPartOf":{"@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/"},"author":{"name":"ideadmin","@id":"https:\/\/progetic.com\/#\/schema\/person\/041af7e621061694b49ff7d28e3c4544"},"headline":"Bombas de calor para viviendas de baja demanda t\u00e9rmica","datePublished":"2020-01-28T12:30:02+00:00","dateModified":"2020-02-21T17:13:51+00:00","mainEntityOfPage":{"@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/"},"wordCount":517,"publisher":{"@id":"https:\/\/progetic.com\/#organization"},"image":{"@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/#primaryimage"},"thumbnailUrl":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/","url":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/","name":"Bombas de calor para viviendas de baja demanda t\u00e9rmica | Progetic","isPartOf":{"@id":"https:\/\/progetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/#primaryimage"},"image":{"@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/#primaryimage"},"thumbnailUrl":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01.jpg","datePublished":"2020-01-28T12:30:02+00:00","dateModified":"2020-02-21T17:13:51+00:00","breadcrumb":{"@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/#primaryimage","url":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01.jpg","contentUrl":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01.jpg","width":828,"height":518,"caption":"Figura 4: C\u00e0lcul de pont t\u00e8rmic, Solera > Mur fa\u00e7ana"},{"@type":"BreadcrumbList","@id":"https:\/\/progetic.com\/es\/blog-es\/bombas-de-calor-para-viviendas-de-baja-demanda-termica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/progetic.com\/es\/"},{"@type":"ListItem","position":2,"name":"Bombas de calor para viviendas de baja demanda t\u00e9rmica"}]},{"@type":"WebSite","@id":"https:\/\/progetic.com\/#website","url":"https:\/\/progetic.com\/","name":"Progetic","description":"Serveis d\u2019enginyeria i consultoria per a edificis de consum gaireb\u00e9 nul i Passivhaus","publisher":{"@id":"https:\/\/progetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/progetic.com\/#organization","name":"Progetic Consultoria Enginyeria","url":"https:\/\/progetic.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/progetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/progetic.com\/wp-content\/uploads\/2019\/12\/Logo_Progetic.svg","contentUrl":"https:\/\/progetic.com\/wp-content\/uploads\/2019\/12\/Logo_Progetic.svg","width":1,"height":1,"caption":"Progetic Consultoria Enginyeria"},"image":{"@id":"https:\/\/progetic.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/ProGETIC-Energy-Solutions\/359464210793572","https:\/\/x.com\/PRoGETIC1"]},{"@type":"Person","@id":"https:\/\/progetic.com\/#\/schema\/person\/041af7e621061694b49ff7d28e3c4544","name":"ideadmin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae84582ea7d3e251d47da463ab876897944800fb26eef1e2abb58ec81acce20f?s=96&d=mm&r=g","caption":"ideadmin"}}]}},"featured_image_src":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01-600x400.jpg","featured_image_src_square":"https:\/\/progetic.com\/wp-content\/uploads\/2020\/01\/progetic_bomba_calor_01-600x518.jpg","author_info":{"display_name":"ideadmin","author_link":"https:\/\/progetic.com\/es\/author\/ideadmin\/"},"_links":{"self":[{"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/posts\/1528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/comments?post=1528"}],"version-history":[{"count":3,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/posts\/1528\/revisions"}],"predecessor-version":[{"id":1824,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/posts\/1528\/revisions\/1824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/media\/1306"}],"wp:attachment":[{"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/media?parent=1528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/categories?post=1528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progetic.com\/es\/wp-json\/wp\/v2\/tags?post=1528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}